{"id":9484,"date":"2024-10-22T01:57:09","date_gmt":"2024-10-21T23:57:09","guid":{"rendered":"https:\/\/noborderseurocup.com\/privacy-policy\/"},"modified":"2024-10-23T13:34:15","modified_gmt":"2024-10-23T11:34:15","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/noborderseurocup.com\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9484\" class=\"elementor elementor-9484 elementor-9395\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69d6bd36 e-flex e-con-boxed e-con e-parent\" data-id=\"69d6bd36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2757419 elementor-widget elementor-widget-text-editor\" data-id=\"2757419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"#privacy_policy\"><strong>Privacy Policy Sito Web<\/strong><\/a>\r\n<a href=\"#informativa_pagina_contatti\"><strong>Informativa Form Pagina \u201cContatti\u201d<\/strong><\/a>\r\n<strong><a href=\"#informativa_newsletter\">Informativa Form \u201cNewsletter\u201d<\/a><\/strong>\r\n<a href=\"#informativa_cookie\"><strong>Cookie Policy<\/strong><\/a>\r\n\r\n<strong>LA PRIVACY POLICY DI QUESTO SITO<\/strong>\r\n\r\n<strong>Informativa ai sensi del Regolamento UE 2016\/679 (\u201cGDPR\u201d)<\/strong>\r\n\r\nNo Borders Euro Cup con il presente documento informa i visitatori del suo Sito Web, nonch\u00e9 gli utenti visitatori delle sue pagine Social, della politica adottata in materia di Protezione dei Dati Personali.\r\n\r\nLa navigazione all\u2019interno di questo Sito Web \u00e8 libera e non richiede nessuna registrazione, con l\u2019eventuale eccezione di alcune aree in cui l\u2019Utente pu\u00f2 liberamente ed espressamente fornire una serie di dati per accedere a servizi specificamente individuati (es. per iscriversi alla newsletter, richiedere informazioni, partecipare a iniziative, ecc.). Per accedere a tali ulteriori servizi, l\u2019Utente sar\u00e0 appositamente informato con indicazione delle ulteriori specifiche finalit\u00e0 e modalit\u00e0 di utilizzo dei dati da parte di No Borders Euro Cup.\r\n\r\nLa presente informativa non \u00e8 valida per altri siti web eventualmente consultabili tramite link presenti su questo sito, sicch\u00e9 No Borders Euro Cup non \u00e8 in alcun modo responsabile del trattamento dei dati effettuato da siti internet di terzi.\r\n\r\n<strong>CHI SIAMO E COME CONTATTARCI: IL \u201cTITOLARE DEL TRATTAMENTO\u201d<\/strong>\r\n\r\nIl \u201c<strong>titolare<\/strong>\u201d del trattamento \u00e8 A\u0160Z-USD JADRAN Basket , con sede in <em>Strada per Vienna 1\/A, 34151 Trieste<\/em> (TS) , contattabile all\u2019indirizzo\u00a0<a href=\"mailto:info@birreriabunker.it\">info@noborderseurocup.com<\/a> o <a href=\"mailto:info@jadranbasket.com\">info@jadranbasket.com<\/a>\u00a0o al numero di Telefono: <em>+39 339 2723168<\/em>.\r\n\r\n<strong>DATI PERSONALI TRATTATI E FINALITA\u2019 DEL TRATTAMENTO<\/strong>\r\n\r\n<strong>Dati di navigazione\u00a0\u00a0<\/strong>\r\n\r\nI sistemi informatici e le procedure software utilizzate per il funzionamento di questo sito acquisiscono alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet.\r\n\r\nIn questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer e dei terminali utilizzati dagli utenti, gli indirizzi in notazione URI\/URL (Uniform Resource Identifier\/Locator) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente.\r\n\r\nTali dati, necessari per la fruizione dei servizi web, vengono anche trattati allo scopo di:\r\n\r\n-ottenere informazioni statistiche anonime sull\u2019uso dei servizi (pagine pi\u00f9 visitate, numero di visitatori per fascia oraria o giornaliera, aree geografiche di provenienza, ecc.);\r\n\r\n-controllare il corretto funzionamento dei servizi offerti.\r\n\r\nI dati di navigazione non persistono per pi\u00f9 di sette giorni e vengono cancellati immediatamente dopo la loro aggregazione (salve eventuali necessit\u00e0 di accertamento di reati da parte dell\u2019Autorit\u00e0 giudiziaria).\r\n\r\n<strong>Dati comunicati dall\u2019Utente<\/strong>\r\n\r\nL\u2019invio facoltativo, esplicito e volontario di messaggi agli indirizzi di contatto pubblicati sul sito web, nonch\u00e9 la compilazione e l\u2019inoltro dei form presenti sul sito web per partecipare a iniziative o godere dei servizi proposti, comportano l\u2019acquisizione dei dati di contatto del mittente, necessari a rispondere, nonch\u00e9 di tutti i dati personali inclusi nelle comunicazioni.\r\n\r\nSpecifiche informative sono pubblicate nelle pagine del sito web predisposte per l\u2019erogazione di determinati servizi, con richiesta di eventuale consenso al trattamento.\r\n\r\n<strong>Dati acquisiti tramite Social<\/strong>\r\n\r\nSe l\u2019Utente si collega a una pagina social di No Borders Euro Cup tramite social login (cio\u00e8 l\u2019account di un social cui \u00e8 iscritto), possono essere acquisiti dalla societ\u00e0 i dati che vengono pubblicati dall\u2019utente in tale social, anche in base alle specifiche impostazioni privacy impostate dall\u2019Utente (ad es. informazioni contenute nel messaggio\/post per rispondere alle richieste di informazioni o assistenza, immagini, ovvero informazioni tratte dal profilo pubblicato).\r\n\r\nSpecifiche informative sul trattamento dei dati svolto dalle piattaforme Social sono rese disponibili dalle stesse (ad es.\u00a0<a href=\"https:\/\/www.facebook.com\/privacy\/explanation\">https:\/\/www.facebook.com\/privacy\/explanation<\/a>;\u00a0<a href=\"https:\/\/twitter.com\/it\/privacy\">https:\/\/twitter.com\/it\/privacy<\/a>;\u00a0<a href=\"https:\/\/help.instagram.com\/519522125107875\">https:\/\/help.instagram.com\/519522125107875<\/a>;\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=it&amp;gl=it\">https:\/\/policies.google.com\/privacy?hl=it&amp;gl=it<\/a>; ).\r\n\r\n<strong>Dati dei minori di anni 16<\/strong>\r\n\r\nI minori di anni 16 non sono autorizzati fornire alcun dato personale, n\u00e9 registrarsi sul sito. Se venisse verificato che le dichiarazioni rese non sono veritiere, si proceder\u00e0 alla cancellazione di tutti i dati ricevuti.\r\n\r\n<strong>SOCIAL NETWORK<\/strong>\r\n\r\nQuesto sito pu\u00f2 utilizzare i c.d. social plug-in. I social plug-in sono speciali strumenti che permettono di incorporare le funzionalit\u00e0 del social network direttamente all\u2019interno del sito web (ad es. la funzione \u201cmi piace\u201d di Facebook). Tutti i social plug-in presenti nel sito sono contrassegnati dal rispettivo logo di propriet\u00e0 della piattaforma di social network (ad es. Facebook, Google, Twitter, Instagram).\r\n\r\nQuando si visita una pagina del nostro sito e si interagisce con il plug-in (ad es. cliccando il pulsante \u201cMi piace\u201d) o si decide di lasciare un commento, le corrispondenti informazioni vengono trasmesse dal browser direttamente alla piattaforma di social network e da questo memorizzate.\r\n\r\nPer informazioni sulle finalit\u00e0, il tipo e le modalit\u00e0 di raccolta, elaborazione, utilizzo e conservazione dei dati personali da parte della piattaforma di social network, nonch\u00e9 per le modalit\u00e0 attraverso cui esercitare i propri diritti, si prega di consultare la politica privacy adottata dal singolo social network\r\n\r\n<strong>Facebook:<\/strong>\u00a0Informativa:\u00a0<a href=\"https:\/\/www.facebook.com\/policies\/cookies\/\">https:\/\/www.facebook.com\/policies\/cookies\/<\/a>\r\n\r\n<strong>Twitter:<\/strong>\u00a0Informativa:\u00a0<a href=\"https:\/\/support.twitter.com\/articles\/20170514\">https:\/\/support.twitter.com\/articles\/20170514<\/a>\r\n\r\n<strong>Instagram:<\/strong>\u00a0Informativa\u00a0<a href=\"https:\/\/help.instagram.com\/519522125107875\">https:\/\/help.instagram.com\/519522125107875<\/a>;\r\n\r\n<strong>Youtube:<\/strong>\u00a0Informativa\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=it&amp;gl=it\"><u>https:\/\/policies.google.com\/privacy?hl=it&amp;gl=it<\/u><\/a>\r\n\r\n<strong>COOKIE<\/strong>\r\n\r\nQuesto Sito pu\u00f2 far utilizzo di strumenti di tracciamento attraverso i cd. cookie. Per maggiori informazioni ed effettuare scelte consapevoli, l\u2019utente pu\u00f2 consultare la informativa dedicata Cookie Policy. CREARE LINK!\r\n\r\n<strong>FINALITA\u2019 E BASE GIURIDICA DEL TRATTAMENTO<\/strong>\r\n\r\nIl Titolare tratta i suindicati dati personali per: gestire e mantenere il sito; permettere accessi ad eventuali aree dedicate; fruire dei servizi eventualmente offerti; fornire assistenza e consulenza e processare una richiesta di contatto; svolgere attivit\u00e0 amministrativo-contabili in genere; adempiere a un ordine dell\u2019Autorit\u00e0; impedire attivit\u00e0 fraudolente o abusi dannosi per il sito; esercitare un diritto in sede giudiziaria.\r\n\r\nIl Titolare pu\u00f2 trattare i suindicati dati personali anche senza specifico consenso, salvo quanto richiesto per la compilazione di specifici form, in quanto la base giuridica di liceit\u00e0 del trattamento deriva dalla esecuzione di misure precontrattuali adottate su richiesta dell\u2019interessato (es. richiesta di informazioni via email), nonch\u00e9 per il perseguimento del legittimo interesse del Titolare di promuovere e realizzare i suoi scopi statutari.\r\n\r\nIl conferimento dei dati per le finalit\u00e0 di cui sopra \u00e8 libero e facoltativo; tuttavia l\u2019eventuale rifiuto pu\u00f2 comportare l\u2019impossibilit\u00e0 da parte del Titolare di dare seguito alla suddetta finalit\u00e0.\r\n\r\n<strong>MODALITA\u2019 DEL TRATTAMENTO<\/strong>\r\n\r\nI dati sono inseriti in una banca dati elettronica e\/o conservati in archivi cartacei.\r\n\r\nI dati non sono oggetto di un processo decisionale automatizzato, n\u00e9 viene effettuata profilazione di alcun tipo.\r\n\r\n<strong>DESTINATARI DEI DATI DEGLI UTENTI<\/strong>\r\n\r\nI dati personali degli utenti potranno essere trattati e conosciuti dai collaboratori e dipendenti di No Boders Euro Cup, quali soggetti autorizzati al trattamento e appositamente istruiti per la tutela della protezione dei dati.\r\n\r\nI dati potranno essere comunicati a soggetti esterni (es. societ\u00e0 che gestiscono il sito e piattaforme web, societ\u00e0 collegate, consulenti esterni, subfornitori, etc.) per le finalit\u00e0 sopra delineate, qualora sussista la necessit\u00e0 del loro coinvolgimento. Gli stessi soggetti opereranno in qualit\u00e0 di Titolari autonomi, o saranno designati come Responsabili esterni del trattamento il cui elenco completo pu\u00f2 essere richiesto inviando una mail a\u00a0<a href=\"mailto:info@noborderseurocup.com\">info@noborderseurocup.com<\/a>.\r\n\r\nI dati potranno esser comunicati a organismi di vigilanza e autorit\u00e0 giudiziarie, nonch\u00e9 a tutti gli altri soggetti ai quali la comunicazione fosse obbligatoria per Legge.\r\n\r\nLa gestione e la conservazione dei dati personali avverr\u00e0 nelle UE, su server ubicati in Italia del Titolare e\/o di societ\u00e0 terze all\u2019interno della UE, incaricate e debitamente nominate quali Responsabili del trattamento.\r\n\r\n<strong>PERIODO DI CONSERVAZIONE DEI DATI<\/strong>\r\n\r\nIl Titolare conserver\u00e0 i dati per il tempo strettamente necessario alla realizzazione delle finalit\u00e0 sopra esplicitate e anche per rispondere a eventuali necessit\u00e0 di accesso e recupero dei dati. Trascorsi 24 mesi dall\u2019acquisizione (7 giorni per i dati di navigazione), ove non vi fossero ulteriori necessit\u00e0 di contatto o obblighi di conservazione (10 anni per finalit\u00e0 contrattuali), i dati verranno cancellati.\r\n\r\n<strong>DIRITTI DELL\u2019INTERESSATO<\/strong>\r\n\r\nTra i diritti riconosciuti rientrano quelli di:\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\"><\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>chiedere l\u2019accesso ai dati personali ed alle informazioni relative agli stessi; la rettifica dei dati inesatti o l\u2019integrazione di quelli incompleti; la cancellazione dei dati personali (al verificarsi di una delle condizioni indicate nell\u2019art. 17, paragrafo 1 del GDPR e nel rispetto delle eccezioni previste nel paragrafo 3 dello stesso articolo); la limitazione del trattamento dei dati personali (al ricorrere di una delle ipotesi indicate nell\u2019art. 18, paragrafo 1 del GDPR);<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>richiedere ed ottenere \u2013 nelle ipotesi in cui la base giuridica del trattamento sia il contratto o il consenso, e lo stesso sia effettuato con mezzi automatizzati \u2013 i dati personali in un formato strutturato e leggibile da dispositivo automatico, anche al fine di comunicare tali dati ad un altro titolare del trattamento (c.d. diritto alla portabilit\u00e0 dei dati personali);<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>opporsi in qualsiasi momento al trattamento dei dati personali al ricorrere di situazioni particolari che lo riguardano;<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>revocare il consenso in qualsiasi momento, limitatamente alle ipotesi in cui il trattamento sia basato sul consenso per una o pi\u00f9 specifiche finalit\u00e0 e riguardi dati personali comuni (ad esempio data e luogo di nascita o luogo di residenza), oppure particolari categorie di dati (ad esempio dati che rivelano lo stato di salute o la vita sessuale). Il trattamento basato sul consenso ed effettuato antecedentemente alla revoca dello stesso conserva, comunque, la sua liceit\u00e0.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\nCon riferimento alle finalit\u00e0 sopra indicate, l\u2019interessato ha la facolt\u00e0 di procedere, in ogni momento, alla richiesta di cessazione del trattamento e all\u2019invio di comunicazioni email da parte del Titolare, con richiesta da presentarsi ai contatti sopra indicati.\r\n\r\n<strong>DIRITTO DI PROPORRE RECLAMO<\/strong>\r\n\r\nSe l\u2019interessato ritiene che sussista una violazione nel trattamento dei Suoi dati personali, pu\u00f2 proporre reclamo all\u2019Autorit\u00e0 di Controllo del luogo in cui abitualmente risiede, lavora o dove si \u00e8 verificata la presunta violazione. In Italia pu\u00f2 proporre reclamo presso l\u2019Autorit\u00e0 Garante per la Protezione dei Dati.\r\n\r\n<strong>MODIFICHE A QUESTA PRIVACY POLICY<\/strong>\r\n\r\nIl Titolare si riserva il diritto di apportare modifiche alla presente privacy policy in qualunque momento notificandolo agli utenti su questa pagina nonch\u00e9, qualora tecnicamente e legalmente fattibile, inviando una comunicazione agli utenti attraverso uno dei dati di contatto di cui \u00e8 in possesso.\r\nQualora le modifiche interessino trattamenti la cui base giuridica \u00e8 il consenso, il Titolare provveder\u00e0 a raccogliere nuovamente il consenso dell\u2019utente, se necessario.\r\n\r\n*\r\n\r\n<strong>DEFINIZIONI<\/strong>\r\n\r\n<strong>Dati Personali (o Dati)<\/strong>\r\n\r\nIl dato personale \u00e8 una qualunque informazione che, direttamente o indirettamente, anche in collegamento con qualsiasi altra informazione, ivi compreso un numero di identificazione personale, renda identificata o identificabile una persona fisica.\r\n\r\n<strong>Dati di Utilizzo<\/strong>\r\n\r\nSono le informazioni raccolte automaticamente attraverso un Sito Web (anche da applicazioni di parti terze integrate in questo Sito Web), tra cui: gli indirizzi IP o i nomi a dominio dei computer utilizzati dall\u2019Utente che si connette al Sito Web, gli indirizzi in notazione URI (Uniform Resource Identifier), l\u2019orario della richiesta, il metodo utilizzato nell\u2019inoltrare la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta dal server (buon fine, errore, ecc.) il paese di provenienza, le caratteristiche del browser e del sistema operativo utilizzati dal visitatore, le varie connotazioni temporali della visita (ad esempio il tempo di permanenza su ciascuna pagina).\r\n\r\n<strong>Utente<\/strong>\r\n\r\nL\u2019individuo che utilizza questo Sito Web che, salvo ove diversamente specificato, coincide con l\u2019Interessato.\r\n\r\n<strong>Interessato<\/strong>\r\n\r\nLa persona fisica cui si riferiscono i Dati Personali.\r\n\r\n<strong>Titolare del Trattamento (o Titolare)<\/strong>\r\n\r\nLa persona fisica o giuridica che determina le finalit\u00e0 e i mezzi del trattamento di dati personali e gli strumenti adottati, ivi comprese le misure di sicurezza relative al funzionamento ed alla fruizione di questo Sito Web. Il Titolare del Trattamento, salvo quanto diversamente specificato, \u00e8 il titolare di questo Sito Web.\r\n\r\n<strong>Responsabile esterno del Trattamento (o Responsabile)<\/strong>\r\n\r\nLa persona fisica, giuridica, la pubblica amministrazione e qualsiasi altro ente che tratta dati personali \u201cper conto\u201d del Titolare.\r\n\r\n<strong>INFORMATIVA PRIVACY\u00a0 \u2013 NEWSLETTER<\/strong>\r\n\r\n<strong>INFORMATIVA PRIVACY<\/strong>\r\n\r\n(AI SENSI DELL\u2019ART. 13 DEL REGOLAMENTO UE 2016\/679)\r\n\r\nLa Newsletter di No Borders Euro Cup \u00e8 distribuita gratuitamente via e-mail agli utenti che ne facciano richiesta compilando il form.\r\n\r\n<strong>CHI SIAMO: IL \u201cTITOLARE DEL TRATTAMENTO\u201d<\/strong>\r\n\r\nIl \u201c<strong>titolare<\/strong>\u201d del trattamento \u00e8 A\u0160Z-USD JADRAN Basket , con sede in <em>Strada per Vienna 1\/A, 34151 Trieste<\/em> (TS) , contattabile all\u2019indirizzo\u00a0<a href=\"mailto:info@birreriabunker.it\">info@noborderseurocup.com<\/a> o <a href=\"mailto:info@jadranbaasket.com\">info@jadranbaasket.com<\/a>\u00a0o al numero di Telefono: <em>+39 339 2723168<\/em>.\r\n\r\n<strong>DATI PERSONALI TRATTATI, FINALITA\u2019 E BASI GIURIDICHE DEL TRATTAMENTO<\/strong>\r\n\r\nCon il Suo esplicito consenso e previa Sua richiesta del servizio, i dati identificativi e l\u2019indirizzo di contatto e-mail saranno oggetto di trattamento per fornire il servizio di Newsletter.\r\n\r\nIl conferimento dei dati per le finalit\u00e0 di cui sopra \u00e8 libero e facoltativo; tuttavia, il mancato conferimento dei dati ha come conseguenza la impossibilit\u00e0 di fornire il servizio corrispondente.\r\n\r\n<strong>MODALITA\u2019 DEL TRATTAMENTO<\/strong>\r\n\r\nI dati sono inseriti in una banca dati elettronica e\/o conservati in archivi cartacei.\r\n\r\nI dati non sono oggetto di un processo decisionale automatizzato, n\u00e9 viene effettuata profilazione di alcun tipo.\r\n\r\n<strong>DESTINATARI DEI DATI<\/strong>\r\n\r\nI dati personali potranno essere conosciuti dai collaboratori e dipendenti della societ\u00e0, quali soggetti autorizzati al trattamento e appositamente istruiti.\r\n\r\nI dati verranno comunicati a societ\u00e0 espressamente nominate come responsabili del trattamento (ad es. piattaforme web per l\u2019inoltro delle e-mail, ovvero per esigenze di manutenzione tecnologica del sito) con apposito contratto o atto giuridico.\r\n\r\n<strong>PERIODO DI CONSERVAZIONE DEI DATI<\/strong>\r\n\r\nLa societ\u00e0 conserver\u00e0 i dati al solo fine di fornire il servizio richiesto e, per tale ragione, saranno conservati esclusivamente per il periodo in cui lo stesso sar\u00e0 attivo e, comunque, non oltre 24 mesi dall\u2019acquisizione.\u00a0 Al decorrere del 24\u00b0 mese, verr\u00e0 inviata una e-mail all\u2019interessato che potr\u00e0 esprimere nuovamente il suo consenso alla prosecuzione del trattamento.\r\n\r\nIl mancato rinnovo del consenso al trattamento dei dati comporter\u00e0 l\u2019impossibilit\u00e0 di continuare ad ottenere il servizio di newsletter.\r\n\r\n<strong>DIRITTI DELL\u2019INTERESSATO<\/strong>\r\n\r\nGli interessati hanno il diritto di ottenere l\u2019accesso ai dati personali e la rettifica o la cancellazione degli stessi o la limitazione del trattamento che li riguarda o di opporsi al trattamento (artt. 15 e ss. del Regolamento).\r\n\r\nGli interessati possono revocare il consenso in qualsiasi momento. Il trattamento basato sul consenso ed effettuato antecedentemente alla revoca della stessa conserva, comunque, la sua liceit\u00e0.\r\n\r\nL\u2019apposita istanza va presentata ai dati di contatto sopra indicati.\r\n\r\nGli interessati, che ritengano che il trattamento dei dati personali a loro riferiti effettuato attraverso questo servizio avvenga in violazione di quanto previsto dal Regolamento, hanno il diritto di proporre reclamo al Garante, o di adire le opportune sedi giudiziarie.\r\n\r\n<strong>CANCELLAZIONE DEL SERVIZIO<\/strong>\r\n\r\n<strong>Per non ricevere pi\u00f9 la Newsletter, potr\u00e0 cancellare la sua iscrizione al servizio in ogni momento grazie al link presente in ciascuna newsletter che le invieremo.<\/strong>\r\n\r\n<strong>INFORMATIVA PRIVACY\u00a0 \u2013 Form Pagina Contatti<\/strong>\r\n\r\n<strong>Informativa ai sensi del Regolamento UE 2016\/679 (\u201cGDPR\u201d)<\/strong>\r\n\r\n<strong>PERCH\u00c9 QUESTO AVVISO<\/strong>\r\n\r\nQuesta informativa ti permetter\u00e0 di conoscere come verranno trattati i dati personali che ci fornisci attraverso la compilazione del form \u201cContatti\u201d di questo sito web.\r\n\r\n<strong>CHI E\u2019 IL TITOLARE DEL TRATTAMENTO<\/strong>\r\n\r\nIl \u201c<strong>titolare<\/strong>\u201d del trattamento \u00e8 A\u0160Z-USD JADRAN Basket , con sede in <em>Strada per Vienna 1\/A, 34151 Trieste<\/em> (TS) , contattabile all\u2019indirizzo\u00a0<a href=\"mailto:info@birreriabunker.it\">info@noborderseurocup.com<\/a> o <a href=\"mailto:info@jadranbaasket.com\">info@jadranbaasket.com<\/a>\u00a0o al numero di Telefono: <em>+39 339 2723168<\/em>.\r\n\r\n<strong>QUALE TIPOLOGIA E NATURA DEI DATI VENGONO TRATTATI<\/strong>\r\n\r\nNel compilare il form sul sito verranno raccolti dati di carattere personale<strong>,<\/strong>\u00a0ovvero dati che consentono una tua identificazione, anche indiretta, quali ad esempio nome, cognome, indirizzo email, o altri dati che rilascerai spontaneamente nel compilare lo spazio libero.\r\n\r\n<strong>DATI DEI MINORI DI ANNI 16<\/strong>\r\n\r\nI minori di anni 16 non sono autorizzati fornire alcun dato personale. Se venisse verificato che le dichiarazioni rese non sono veritiere, si proceder\u00e0 alla cancellazione di tutti i dati ricevuti.\r\n\r\n<strong>FINALITA\u2019 E BASI GIURIDICHE DI LICEITA\u2019 DEL TRATTAMENTO<\/strong>\r\n\r\nI dati raccolti saranno utilizzati per le seguenti finalit\u00e0:\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\"><\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>per consentirci il rilascio di informazioni su tua richiesta.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>per l\u2019esecuzione del servizio richiesto.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\nI dati di natura comune potranno essere trattati anche senza il tuo specifico consenso e ci\u00f2 per soddisfare le tue richieste e per le finalit\u00e0 precontrattuali e contrattuali connesse e strumentali al servizio richiesto, nonch\u00e9 per adempiere ai correlati obblighi legali cui \u00e8 soggetto il Titolare del trattamento.\r\n\r\nSei libero di fornire o meno i tuoi dati, ma in mancanza dei dati richiesti non sar\u00e0 possibile concludere o dare esecuzione al servizio e alle tue richieste.\r\n\r\n<strong>MODALITA\u2019 e LUOGO DI TRATTAMENTO e PERIODO DI CONSERVAZIONE<\/strong>\r\n\r\nIl trattamento dei tuoi dati avviene presso la nostra sede, mediante impiego di strumenti telematici, cartacei, elettronici o automatizzati e viene effettuato dai soggetti autorizzati e istruiti nei limiti dell\u2019incarico loro conferito, per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti.\r\n\r\nI tuoi dati, in particolare, saranno conservati per il periodo di durata dell\u2019eventuale contratto e, successivamente, per il tempo necessario per adempiere a obblighi fiscali, o per altre finalit\u00e0 previste da norme di legge o regolamento. In difetto di stipula di un contratto, i dati verranno cancellati dopo 12 mesi dalla raccolta.\r\n\r\n<strong>COMUNICAZIONE E DIFFUSIONE DEI DATI<\/strong>\r\n\r\nI tuoi dati personali potranno essere comunicati a societ\u00e0 di elaborazione dati e servizi informatici, professionisti, societ\u00e0 o studi di consulenza, societ\u00e0 operanti nella fornitura di servizi per l\u2019esecuzione del contratto. Tali soggetti opereranno in qualit\u00e0 di Titolari autonomi, o saranno designati come Responsabili del trattamento con apposito contratto o atto giuridico.\r\n\r\nPotranno poi accedere ai dati i soggetti ai quali sia accordata questa facolt\u00e0 da disposizioni di legge o regolamenti (es. autorit\u00e0 di pubblica sicurezza).\r\n\r\nI dati non saranno oggetto di un processo decisionale automatizzato, n\u00e9 verr\u00e0 effettuata profilazione di alcun tipo.\r\n\r\nI dati personali non saranno soggetti a diffusione, n\u00e9 verranno trasferiti in paesi terzi o ad organizzazioni internazionali\r\n\r\n<strong>DIRITTI DELL\u2019INTERESSATO<\/strong>\r\n\r\nTra i diritti a te riconosciuti rientrano quelli di:\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\"><\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>chiedere l\u2019accesso ai tuoi dati personali ed alle informazioni relative agli stessi; la rettifica dei dati inesatti o l\u2019integrazione di quelli incompleti; la cancellazione dei dati personali (al verificarsi di una delle condizioni indicate nell\u2019art. 17, paragrafo 1 del GDPR e nel rispetto delle eccezioni previste nel paragrafo 3 dello stesso articolo); la limitazione del trattamento dei dati personali (al ricorrere di una delle ipotesi indicate nell\u2019art. 18, paragrafo 1 del GDPR);<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>richiedere ed ottenere \u2013 nelle ipotesi in cui la base giuridica del trattamento sia il contratto o il consenso, e lo stesso sia effettuato con mezzi automatizzati \u2013 i dati personali in un formato strutturato e leggibile da dispositivo automatico, anche al fine di comunicare tali dati ad un altro titolare del trattamento (c.d. diritto alla portabilit\u00e0 dei dati personali);<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>opporsi in qualsiasi momento al trattamento dei dati personali, compresa la profilazione, al ricorrere di situazioni particolari che lo riguardano;<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n \t<li>revocare il consenso in qualsiasi momento, limitatamente alle ipotesi in cui il trattamento sia basato sul consenso per una o pi\u00f9 specifiche finalit\u00e0 e riguardi dati personali comuni (ad esempio data e luogo di nascita o luogo di residenza), oppure particolari categorie di dati (ad esempio dati che rivelano lo stato di salute o la vita sessuale). Il trattamento basato sul consenso ed effettuato antecedentemente alla revoca dello stesso conserva, comunque, la sua liceit\u00e0;<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\nLe tue richieste vanno rivolte ai dati di contatto sopra indicati.\r\n\r\nSe ritieni che sussista una violazione nel trattamento dei tuoi dati personali, puoi proporre reclamo all\u2019Autorit\u00e0 di Controllo del luogo in cui abitualmente risiedi, lavori o dove si \u00e8 verificata la presunta violazione. Ti informiamo che in Italia puoi proporre reclamo presso l\u2019Autorit\u00e0 Garante per la Protezione dei Dati.\r\n<div id=\"gtx-trans\" style=\"position: absolute; left: -5px; top: -10px;\">\r\n<div class=\"gtx-trans-icon\"><\/div>\r\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-711ebab elementor-widget elementor-widget-spacer\" data-id=\"711ebab\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"informativa_cookie\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b70ac3 elementor-widget elementor-widget-text-editor\" data-id=\"2b70ac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"font-weight: bolder;\">INFORMATIVA ESTESA SUI COOKIE<\/span><\/h2>\r\nQuesto sito utilizza cookie, anche di terze parti, per migliorarne l\u2019esperienza di navigazione e consentire a chi naviga di usufruire dei nostri servizi online e di visualizzare pubblicit\u00e0 in linea con le proprie preferenze. I cookies utilizzati in questo sito rientrano nelle categorie descritte di seguito.\r\n\r\n<span style=\"font-weight: bolder;\">Cosa sono i cookies<\/span>\r\n\r\nI cookies sono piccoli file di testo che vengono automaticamente posizionati sul PC del navigatore all\u2019interno del browser. Essi contengono informazioni di base sulla navigazione in Internet e grazie al browser vengono riconosciuti ogni volta che l\u2019utente visita il sito.\r\n\r\nDi seguito vengono forniti dettagli sui cookie installati da questo sito e indicazioni su come gestire le preferenze in merito ad essi.\r\n\r\n<span style=\"font-weight: bolder;\">Gestione dei cookie<\/span>\r\n\r\n<span style=\"font-weight: bolder;\">1 \u2013 Cookie tecnici<\/span>\r\n\r\nI cookie tecnici descritti qui di seguito non richiedono consenso perci\u00f2 vengono installati automaticamente a seguito dell\u2019accesso al sito.\r\n<ul class=\"wp-block-list\" style=\"font-size: 18px; background-color: #ffffff;\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\" style=\"font-size: 18px; background-color: #ffffff;\">\r\n \t<li style=\"font-size: 18px;\">Cookie necessari al funzionamento: cookies che permettono al sito di funzionare correttamente anche consentendo all\u2019utente di avere un\u2019esperienza di navigazione funzionale. Ad esempio, mantengono l\u2019utente collegato durante la navigazione evitando che il sito richieda di collegarsi pi\u00f9 volte per accedere alle pagine successive.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\" style=\"font-size: 18px; background-color: #ffffff;\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\" style=\"font-size: 18px; background-color: #ffffff;\">\r\n \t<li style=\"font-size: 18px;\">Cookie per il salvataggio delle preferenze: cookie che permettono di ricordare le preferenze selezionate dall\u2019utente durante la navigazione, ad esempio, consentono di impostare la lingua.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<ul class=\"wp-block-list\" style=\"font-size: 18px; background-color: #ffffff;\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\" style=\"font-size: 18px; background-color: #ffffff;\">\r\n \t<li style=\"font-size: 18px;\">Cookie statistici e di misurazione dell\u2019audience: cookie che aiutano a capire, attraverso dati raccolti in forma anonima e aggregata, come gli utenti interagiscono con il sito internet fornendo informazioni relative alle sezioni visitate, il tempo trascorso sul sito, eventuali malfunzionamenti.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<span style=\"font-weight: bolder;\">2 \u2013 Cookie di terze parti<\/span>\r\n\r\nAttraverso questo sito vengono installati anche cookie gestiti da terze parti.\r\n\r\nPer informazioni relative a questi cookie di terze parti e la gestione del consenso sono disponibili gli appositi link delle tabelle riportate pi\u00f9 sotto. Inoltre accedendo alla pagina http:\/\/www.youronlinechoices.com\/it\/le-tue-scelte \u00e8 possibile informarsi sulla pubblicit\u00e0 comportamentale oltre che disattivare o attivare i cookie delle societ\u00e0 elencate che lavorano con i gestori dei siti web per raccogliere e utilizzare informazioni utili alla fruizione della pubblicit\u00e0.\r\n\r\nCookie Statistici e di Misurazione dell\u2019audience di terze parti\r\n\r\nQuesti cookie forniscono informazioni anonime\/aggregate sul modo in cui i visitatori navigano sul sito. Di seguito i link alle rispettive pagine di cookies policy per gestire il consenso.\r\n\r\n<span style=\"font-weight: bolder;\">Google\r\n<\/span><span style=\"font-weight: bolder;\">Google Analytics: sistema di statistiche<\/span>\r\nCookies analitici\r\n<a href=\"https:\/\/policies.google.com\/technologies\/partner-sites\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\nQuesti cookie di terze parti \u2013 qualora presenti i collegamenti sul sito \u2013 vengono utilizzati per integrare alcune diffuse funzionalit\u00e0 dei principali social media e fornirle all\u2019interno del sito. In particolare permettono la registrazione e l\u2019autenticazione sul sito tramite facebook e google connect, la condivisione e i commenti di pagine del sito sui social, abilitano le funzionalit\u00e0 del \u201cmi piace\u201d su Facebook e del \u201c+1\u201d su G+. Di seguito i link alle rispettive pagine di cookies policy per gestire il consenso.\r\n\r\n<span style=\"font-weight: bolder;\">Facebook\r\n<\/span>social media\r\n<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\n<span style=\"font-weight: bolder;\">G+\u00a0<\/span>\r\nsocial media\r\n<a href=\"https:\/\/policies.google.com\/technologies\/partner-sites\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\n<span style=\"font-weight: bolder;\">Youtube<\/span>\r\nsocial media\r\nprivacy policy\r\n\r\n<span style=\"font-weight: bolder;\">Twitter<\/span>\r\nsocial media\r\n<a href=\"https:\/\/twitter.com\/it\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\n<span style=\"font-weight: bolder;\">Linkedin<\/span>\r\nsocial media\r\n<a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\n<span style=\"font-weight: bolder;\">Pinterest<\/span>\r\nsocial media\r\n<a href=\"https:\/\/policy.pinterest.com\/en\/privacy-policy\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\n<span style=\"font-weight: bolder;\">Cookie di remarketing<\/span>\r\n\r\nQuesti cookie di terza parte, quando presenti, consentono di mostrare annunci pubblicitari basati sugli interessi manifestati dagli utenti durante la navigazione online sui siti e le APP appartenenti al circuito della terza parte che ha rilasciato questi cookie. Per esempio, i cookie di remarketing utilizzati da questo sito possono essere quelli della Rete Display di Google e della piattaforma Audience Network di Facebook. Qui sotto vengono forniti i link per disattivare l\u2019utilizzo dei cookie da parte di Google e di Facebook.\r\n\r\n<span style=\"font-weight: bolder;\">Google\r\n<\/span>Remarketing\r\n<a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\n<span style=\"font-weight: bolder;\">Facebook\r\n<\/span>Remarketing\r\n<a href=\"https:\/\/www.facebook.com\/ds\/preferences\/?entry_product=ad_settings_screen&amp;expand_ad_settings=1\" target=\"_blank\" rel=\"noreferrer noopener\">privacy policy<\/a>\r\n\r\nCookie analitici di terze parti per il servizio \u201cBusiness Contact\u201d\r\n\r\nQuesti cookie di terze parti, quando presenti, consentono di tracciare le visite sul presente sito effettuate da aziende che abbiano registrato un IP fisso. Le informazioni pubbliche relative all\u2019IP fisso posso essere utilizzate, insieme ad altri dati pubblici, per contattare le aziende che hanno dimostrato interesse a prodotti e servizi offerti dal presente sito.\r\n\r\nIl servizio \u00e8 identificato con il nome \u201cBusiness Contact\u201d e prevede l\u2019installazione dei seguenti cookie:\r\n\r\n__bctc\r\n\r\n__bcvc\r\n\r\n__bcsc\r\n\r\n__ddtest\r\n\r\n<span style=\"font-weight: bolder;\">3 \u2013 Ricordati che puoi gestire le tue preferenze sui cookie anche attraverso il browser<\/span>\r\n\r\nSe si utilizza Internet Explorer\r\n\r\nIn Internet Explorer, fare clic su \u201cStrumenti\u201d e selazionare \u201cOpzioni Internet\u201d. Nella scheda Privacy, spostare il cursore verso l\u2019alto per bloccare tutti i cookie o verso il basso per consentire tutti i cookie, e quindi fare clic su OK.\r\n\r\nSe si utilizza il browser Firefox\r\n\r\nScegliere il men\u00f9 \u201cStrumenti\u201d del browser e selezionare il menu \u201cOpzioni\u201d. Fare clic sulla scheda \u201cPrivacy\u201d. Nell\u2019elenco a discesa \u201cRegole di conservazione\u201d selezionare il livello desiderato. Spuntare la casella \u201cAccettare i cookie\u201d per attivare i cookie, o togliere la spunta per disattivarli. Scegliere per quanto tempo i cookie possono essere conservati.\r\n\r\nSe si utilizza il browser Safari\r\n\r\nCliccare nel Men\u00f9 Safari, selezionare il menu \u201cModifica\u201d e selezionare \u201cPreferences\u201d. Cliccare su \u201cPrivacy\u201d. Posizionare l\u2019impostazione \u201ccookies Block\u201d e fare clic su OK.\r\n\r\nSe si utilizza il browser Google Chrome\r\n\r\nCliccare sul menu Chrome nella barra degli strumenti del browser. Selezionare \u201cImpostazioni\u201d. Cliccare su \u201cMostra impostazioni avanzate\u201d. Nella sezione \u201cPrivacy\u201d, cliccare su \u201cImpostazioni contenuti\u201d. Nella sezione \u201cCookies\u201d, selezionare \u201cImpedisci a tutti i siti di salvare i dati\u201d e quindi fare clic su OK.\r\n\r\nSe usi un qualsiasi altro browser o non conosci il tipo e versione di browser che stai utilizzando, clicca \u201cAiuto\u201d nella finestra del browser in alto, da cui puoi accedere a tutte le informazioni necessarie.\r\n\r\nAi sensi degli artt. 15-22 del GDPR, l\u2019utente ha il diritto di richiedere, scrivendo all\u2019indirizzo del titolare del presente sito, l\u2019accesso ai suoi dati personali, la rettifica o la cancellazione degli stessi o anche semplicemente la limitazione del loro trattamento (anonimizzazione) o proporre reclamo all\u2019Autorit\u00e0 Garante per la Protezione dei Dati, qualora ritenesse siano stati violati i suoi diritti. Per modificare o cancellare i soli dati che sono archiviati sui sistemi che erogano il presente sito, scrivere a\u00a0<a href=\"mailto:info@noborderseurocup.com\">info@noborderseurocup.com<\/a>.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Sito Web Informativa Form Pagina \u201cContatti\u201d Informativa Form \u201cNewsletter\u201d Cookie Policy LA PRIVACY POLICY DI QUESTO SITO Informativa ai sensi del Regolamento UE 2016\/679 (\u201cGDPR\u201d) No Borders Euro Cup con il presente documento informa i visitatori del suo Sito Web, nonch\u00e9 gli utenti visitatori delle sue pagine Social, della politica adottata in materia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9484","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - No Borders Euro Cup<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noborderseurocup.com\/en\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - No Borders Euro Cup\" \/>\n<meta property=\"og:description\" content=\"Privacy Policy Sito Web Informativa Form Pagina \u201cContatti\u201d Informativa Form \u201cNewsletter\u201d Cookie Policy LA PRIVACY POLICY DI QUESTO SITO Informativa ai sensi del Regolamento UE 2016\/679 (\u201cGDPR\u201d) No Borders Euro Cup con il presente documento informa i visitatori del suo Sito Web, nonch\u00e9 gli utenti visitatori delle sue pagine Social, della politica adottata in materia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noborderseurocup.com\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"No Borders Euro Cup\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/people\/No-Borders-Euro-Cup\/61566675292286\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T11:34:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noborderseurocup.com\/wp-content\/uploads\/2024\/10\/nbec_ft_image_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - No Borders Euro Cup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/#website\"},\"datePublished\":\"2024-10-21T23:57:09+00:00\",\"dateModified\":\"2024-10-23T11:34:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/\",\"name\":\"No Borders Euro Cup - Official Page of the Tournament\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/#organization\",\"name\":\"NBEC - No Borders Euro Cup\",\"url\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noborderseurocup.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/noborderseurocup-logo-shadow-1-600w.png\",\"contentUrl\":\"https:\\\/\\\/noborderseurocup.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/noborderseurocup-logo-shadow-1-600w.png\",\"width\":600,\"height\":908,\"caption\":\"NBEC - No Borders Euro Cup\"},\"image\":{\"@id\":\"https:\\\/\\\/noborderseurocup.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/people\\\/No-Borders-Euro-Cup\\\/61566675292286\\\/\",\"https:\\\/\\\/www.instagram.com\\\/noborderseurocupofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - No Borders Euro Cup","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noborderseurocup.com\/en\/privacy-policy\/","og_locale":"en_US","og_type":"article","og_title":"Privacy Policy - No Borders Euro Cup","og_description":"Privacy Policy Sito Web Informativa Form Pagina \u201cContatti\u201d Informativa Form \u201cNewsletter\u201d Cookie Policy LA PRIVACY POLICY DI QUESTO SITO Informativa ai sensi del Regolamento UE 2016\/679 (\u201cGDPR\u201d) No Borders Euro Cup con il presente documento informa i visitatori del suo Sito Web, nonch\u00e9 gli utenti visitatori delle sue pagine Social, della politica adottata in materia [&hellip;]","og_url":"https:\/\/noborderseurocup.com\/en\/privacy-policy\/","og_site_name":"No Borders Euro Cup","article_publisher":"https:\/\/facebook.com\/people\/No-Borders-Euro-Cup\/61566675292286\/","article_modified_time":"2024-10-23T11:34:15+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/noborderseurocup.com\/wp-content\/uploads\/2024\/10\/nbec_ft_image_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/noborderseurocup.com\/en\/privacy-policy\/","url":"https:\/\/noborderseurocup.com\/en\/privacy-policy\/","name":"Privacy Policy - No Borders Euro Cup","isPartOf":{"@id":"https:\/\/noborderseurocup.com\/en\/#website"},"datePublished":"2024-10-21T23:57:09+00:00","dateModified":"2024-10-23T11:34:15+00:00","breadcrumb":{"@id":"https:\/\/noborderseurocup.com\/en\/privacy-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noborderseurocup.com\/en\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noborderseurocup.com\/en\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noborderseurocup.com\/en\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/noborderseurocup.com\/en\/#website","url":"https:\/\/noborderseurocup.com\/en\/","name":"No Borders Euro Cup - Official Page of the Tournament","description":"","publisher":{"@id":"https:\/\/noborderseurocup.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noborderseurocup.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/noborderseurocup.com\/en\/#organization","name":"NBEC - No Borders Euro Cup","url":"https:\/\/noborderseurocup.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/noborderseurocup.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/noborderseurocup.com\/wp-content\/uploads\/2024\/10\/noborderseurocup-logo-shadow-1-600w.png","contentUrl":"https:\/\/noborderseurocup.com\/wp-content\/uploads\/2024\/10\/noborderseurocup-logo-shadow-1-600w.png","width":600,"height":908,"caption":"NBEC - No Borders Euro Cup"},"image":{"@id":"https:\/\/noborderseurocup.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/people\/No-Borders-Euro-Cup\/61566675292286\/","https:\/\/www.instagram.com\/noborderseurocupofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/pages\/9484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/comments?post=9484"}],"version-history":[{"count":7,"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/pages\/9484\/revisions"}],"predecessor-version":[{"id":9684,"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/pages\/9484\/revisions\/9684"}],"wp:attachment":[{"href":"https:\/\/noborderseurocup.com\/en\/wp-json\/wp\/v2\/media?parent=9484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}